{"id":15448,"date":"2025-09-04T10:43:17","date_gmt":"2025-09-04T15:43:17","guid":{"rendered":"https:\/\/www.kusd.edu\/whittier\/venue\/indian-trail-high-school-and-academy\/"},"modified":"2026-07-14T20:10:29","modified_gmt":"2026-07-15T01:10:29","slug":"indian-trail-high-school-and-academy","status":"publish","type":"tribe_venue","link":"https:\/\/www.kusd.edu\/whittier\/venue\/indian-trail-high-school-and-academy\/","title":{"rendered":"Indian Trail High School and Academy"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-15448","tribe_venue","type-tribe_venue","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.kusd.edu\/whittier\/wp-json\/wp\/v2\/tribe_venue\/15448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kusd.edu\/whittier\/wp-json\/wp\/v2\/tribe_venue"}],"about":[{"href":"https:\/\/www.kusd.edu\/whittier\/wp-json\/wp\/v2\/types\/tribe_venue"}],"version-history":[{"count":1,"href":"https:\/\/www.kusd.edu\/whittier\/wp-json\/wp\/v2\/tribe_venue\/15448\/revisions"}],"predecessor-version":[{"id":15462,"href":"https:\/\/www.kusd.edu\/whittier\/wp-json\/wp\/v2\/tribe_venue\/15448\/revisions\/15462"}],"wp:attachment":[{"href":"https:\/\/www.kusd.edu\/whittier\/wp-json\/wp\/v2\/media?parent=15448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}