{"id":16182,"date":"2024-04-24T11:12:44","date_gmt":"2024-04-24T16:12:44","guid":{"rendered":"https:\/\/www.kusd.edu\/tremper\/wp-content\/uploads\/sites\/43\/2024\/04\/news-communications-academy-showcase.png"},"modified":"2024-04-24T11:12:44","modified_gmt":"2024-04-24T16:12:44","slug":"news-communications-academy-showcase","status":"inherit","type":"attachment","link":"https:\/\/www.kusd.edu\/tremper\/news-communications-academy-showcase\/","title":{"rendered":"news-communications-academy-showcase"},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"class_list":["post-16182","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.kusd.edu\/tremper\/wp-content\/uploads\/sites\/43\/2024\/04\/news-communications-academy-showcase.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.kusd.edu\/tremper\/wp-content\/uploads\/sites\/43\/2024\/04\/news-communications-academy-showcase-300x300.png\" class=\"attachment-medium size-medium\" alt=\"Indian Trail Communications Academy Showcase - May 17\" srcset=\"https:\/\/www.kusd.edu\/tremper\/wp-content\/uploads\/sites\/43\/2024\/04\/news-communications-academy-showcase-300x300.png 300w, https:\/\/www.kusd.edu\/tremper\/wp-content\/uploads\/sites\/43\/2024\/04\/news-communications-academy-showcase-150x150.png 150w, https:\/\/www.kusd.edu\/tremper\/wp-content\/uploads\/sites\/43\/2024\/04\/news-communications-academy-showcase-768x768.png 768w, https:\/\/www.kusd.edu\/tremper\/wp-content\/uploads\/sites\/43\/2024\/04\/news-communications-academy-showcase.png 792w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Indian Trail Communications Academy Showcase - May 17","media_type":"image","mime_type":"image\/png","media_details":{"width":792,"height":792,"file":"2024\/04\/news-communications-academy-showcase.png","filesize":588457,"sizes":{"medium":{"file":"news-communications-academy-showcase-300x300.png","width":300,"height":300,"filesize":102157,"mime_type":"image\/png","source_url":"https:\/\/www.kusd.edu\/tremper\/wp-content\/uploads\/sites\/43\/2024\/04\/news-communications-academy-showcase-300x300.png"},"thumbnail":{"file":"news-communications-academy-showcase-150x150.png","width":150,"height":150,"filesize":30542,"mime_type":"image\/png","source_url":"https:\/\/www.kusd.edu\/tremper\/wp-content\/uploads\/sites\/43\/2024\/04\/news-communications-academy-showcase-150x150.png"},"medium_large":{"file":"news-communications-academy-showcase-768x768.png","width":768,"height":768,"filesize":544885,"mime_type":"image\/png","source_url":"https:\/\/www.kusd.edu\/tremper\/wp-content\/uploads\/sites\/43\/2024\/04\/news-communications-academy-showcase-768x768.png"},"full":{"file":"news-communications-academy-showcase.png","width":792,"height":792,"mime_type":"image\/png","source_url":"https:\/\/www.kusd.edu\/tremper\/wp-content\/uploads\/sites\/43\/2024\/04\/news-communications-academy-showcase.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.kusd.edu\/tremper\/wp-content\/uploads\/sites\/43\/2024\/04\/news-communications-academy-showcase.png","filename":"news-communications-academy-showcase.png","filesize":588457,"_links":{"self":[{"href":"https:\/\/www.kusd.edu\/tremper\/wp-json\/wp\/v2\/media\/16182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kusd.edu\/tremper\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.kusd.edu\/tremper\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.kusd.edu\/tremper\/wp-json\/wp\/v2\/users\/3"}]}}